{"id":4058,"date":"2015-11-17T14:53:43","date_gmt":"2015-11-17T14:53:43","guid":{"rendered":"http:\/\/tabernaculoprensadedios.com\/web\/?p=4058"},"modified":"2015-11-17T14:53:43","modified_gmt":"2015-11-17T14:53:43","slug":"nuestra-esperanza-gloriosa","status":"publish","type":"post","link":"https:\/\/tabernaculoprensadedios.com\/web\/nuestra-esperanza-gloriosa\/","title":{"rendered":"Nuestra Esperanza Gloriosa"},"content":{"rendered":"<p>1 CORINTIOS 15.20-58<\/p>\n<p>Cuando escuchamos la palabra resurrecci\u00f3n, la mayor\u00eda de nosotros piensa en Cristo resucitando de los muertos, pero su victoria sobre la tumba demuestra lo que suceder\u00e1 con nosotros, tambi\u00e9n.<\/p>\n<p>Cuando escuchamos la palabra resurrecci\u00f3n, la mayor\u00eda de nosotros piensa en Cristo resucitando de los muertos, pero su victoria sobre la tumba demuestra lo que suceder\u00e1 con nosotros, tambi\u00e9n.<\/p>\n<p>Un d\u00eda, cada persona que haya muerto experimentar\u00e1 una resurrecci\u00f3n corporal como la de Cristo, y quienes est\u00e9n vivos cuando \u00c9l regrese, ser\u00e1n transformados de mortales a inmortales en un abrir y cerrar de ojos.<\/p>\n<p>Una de las primeras preguntas que nos viene a la mente es: \u00bfQu\u00e9 aspecto tendr\u00e9? No puedo responder a eso espec\u00edficamente, pero lo \u00fanico que s\u00e9 es que luciremos lo mejor que el Creador pueda hacernos.<\/p>\n<p>Estos humildes cuerpos terrenales ser\u00e1n transformados en cuerpos gloriosos como el de \u00c9l. Los escritos del ap\u00f3stol Pablo ofrecen algunas pistas acerca de sus caracter\u00edsticas: ser\u00e1n imperecederos, gloriosos, poderosos y espirituales.<\/p>\n<p>Como tales, ser\u00e1n ideales para vivir en el cielo. Nunca experimentaremos de nuevo el pecado, la enfermedad, el dolor, el sufrimiento, la debilidad, el agotamiento y la muerte.<\/p>\n<p>A veces, las personas me preguntan si seremos reconocibles, es decir, si reconoceremos a nuestros seres queridos, y si ellos nos reconocer\u00e1n a nosotros.<\/p>\n<p>Considere lo siguiente: \u00bfC\u00f3mo podr\u00edan unos cuerpos tan poderosos y gloriosos estar limitados, si estar\u00e1n tan avanzados en todo lo dem\u00e1s? Estoy plenamente convencido de que todos nuestros sentidos y capacidades mentales ser\u00e1n mejorados, no disminuidos.<\/p>\n<p>Nos espera un futuro glorioso, pero el gozo de un nuevo cuerpo, y el reencuentro con nuestros seres queridos, ser\u00e1 sobrepasado por la emoci\u00f3n de ver a Dios. \u00c9l es quien hizo todo esto posible. En agradecimiento, am\u00e9mosle y sirv\u00e1mosle con fidelidad mientras sigamos estando en esta tierra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1 CORINTIOS 15.20-58 Cuando escuchamos la palabra resurrecci\u00f3n, la mayor\u00eda de nosotros piensa en Cristo resucitando de los muertos, pero su victoria sobre la tumba demuestra lo que suceder\u00e1 con nosotros, tambi\u00e9n. Cuando escuchamos la palabra resurrecci\u00f3n, la mayor\u00eda de nosotros piensa en Cristo resucitando de los muertos, pero su victoria sobre la tumba demuestra &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4058","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nuestra Esperanza Gloriosa - Tabernaculo Prensa de Dios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tabernaculoprensadedios.com\/web\/nuestra-esperanza-gloriosa\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Nuestra Esperanza Gloriosa\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"1 CORINTIOS 15.20-58 Cuando escuchamos la palabra resurrecci\u00f3n, la mayor\u00eda de nosotros piensa en Cristo resucitando de los muertos, pero su victoria sobre la tumba demuestra lo que suceder\u00e1 con nosotros, tambi\u00e9n. Cuando escuchamos la palabra resurrecci\u00f3n, la mayor\u00eda de nosotros piensa en Cristo resucitando de los muertos, pero su victoria sobre la tumba demuestra &hellip;\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tabernaculoprensadedios.com\/web\/nuestra-esperanza-gloriosa\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Tabernaculo Prensa de Dios\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-17T14:53:43+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"tabernaculo\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:creator\" content=\"@PrensadeDios\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:site\" content=\"@PrensadeDios\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"tabernaculo\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/nuestra-esperanza-gloriosa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/nuestra-esperanza-gloriosa\\\/\"},\"author\":{\"name\":\"tabernaculo\",\"@id\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/#\\\/schema\\\/person\\\/bc0e069fef56b38e177db6f098ae0b6e\"},\"headline\":\"Nuestra Esperanza Gloriosa\",\"datePublished\":\"2015-11-17T14:53:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/nuestra-esperanza-gloriosa\\\/\"},\"wordCount\":326,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/#\\\/schema\\\/person\\\/bc0e069fef56b38e177db6f098ae0b6e\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/nuestra-esperanza-gloriosa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/nuestra-esperanza-gloriosa\\\/\",\"url\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/nuestra-esperanza-gloriosa\\\/\",\"name\":\"Nuestra Esperanza Gloriosa - Tabernaculo Prensa de Dios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/#website\"},\"datePublished\":\"2015-11-17T14:53:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/nuestra-esperanza-gloriosa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/nuestra-esperanza-gloriosa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/nuestra-esperanza-gloriosa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestra Esperanza Gloriosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/\",\"name\":\"Tabernaculo Prensa de Dios\",\"description\":\"Un medio a la manera de Dios\",\"publisher\":{\"@id\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/#\\\/schema\\\/person\\\/bc0e069fef56b38e177db6f098ae0b6e\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/#\\\/schema\\\/person\\\/bc0e069fef56b38e177db6f098ae0b6e\",\"name\":\"tabernaculo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/login-logo1.png\",\"url\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/login-logo1.png\",\"contentUrl\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/login-logo1.png\",\"width\":300,\"height\":118,\"caption\":\"tabernaculo\"},\"logo\":{\"@id\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/login-logo1.png\"},\"url\":\"https:\\\/\\\/tabernaculoprensadedios.com\\\/web\\\/author\\\/tabernaculo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nuestra Esperanza Gloriosa - Tabernaculo Prensa de Dios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tabernaculoprensadedios.com\/web\/nuestra-esperanza-gloriosa\/","og_locale":"es_ES","og_type":"article","og_title":"Nuestra Esperanza Gloriosa","og_description":"1 CORINTIOS 15.20-58 Cuando escuchamos la palabra resurrecci\u00f3n, la mayor\u00eda de nosotros piensa en Cristo resucitando de los muertos, pero su victoria sobre la tumba demuestra lo que suceder\u00e1 con nosotros, tambi\u00e9n. Cuando escuchamos la palabra resurrecci\u00f3n, la mayor\u00eda de nosotros piensa en Cristo resucitando de los muertos, pero su victoria sobre la tumba demuestra &hellip;","og_url":"https:\/\/tabernaculoprensadedios.com\/web\/nuestra-esperanza-gloriosa\/","og_site_name":"Tabernaculo Prensa de Dios","article_published_time":"2015-11-17T14:53:43+00:00","author":"tabernaculo","twitter_card":"summary_large_image","twitter_creator":"@PrensadeDios","twitter_site":"@PrensadeDios","twitter_misc":{"Escrito por":"tabernaculo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tabernaculoprensadedios.com\/web\/nuestra-esperanza-gloriosa\/#article","isPartOf":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/nuestra-esperanza-gloriosa\/"},"author":{"name":"tabernaculo","@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e"},"headline":"Nuestra Esperanza Gloriosa","datePublished":"2015-11-17T14:53:43+00:00","mainEntityOfPage":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/nuestra-esperanza-gloriosa\/"},"wordCount":326,"commentCount":0,"publisher":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e"},"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tabernaculoprensadedios.com\/web\/nuestra-esperanza-gloriosa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tabernaculoprensadedios.com\/web\/nuestra-esperanza-gloriosa\/","url":"https:\/\/tabernaculoprensadedios.com\/web\/nuestra-esperanza-gloriosa\/","name":"Nuestra Esperanza Gloriosa - Tabernaculo Prensa de Dios","isPartOf":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#website"},"datePublished":"2015-11-17T14:53:43+00:00","breadcrumb":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/nuestra-esperanza-gloriosa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tabernaculoprensadedios.com\/web\/nuestra-esperanza-gloriosa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tabernaculoprensadedios.com\/web\/nuestra-esperanza-gloriosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tabernaculoprensadedios.com\/web\/"},{"@type":"ListItem","position":2,"name":"Nuestra Esperanza Gloriosa"}]},{"@type":"WebSite","@id":"https:\/\/tabernaculoprensadedios.com\/web\/#website","url":"https:\/\/tabernaculoprensadedios.com\/web\/","name":"Tabernaculo Prensa de Dios","description":"Un medio a la manera de Dios","publisher":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tabernaculoprensadedios.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e","name":"tabernaculo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png","url":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png","contentUrl":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png","width":300,"height":118,"caption":"tabernaculo"},"logo":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png"},"url":"https:\/\/tabernaculoprensadedios.com\/web\/author\/tabernaculo\/"}]}},"_links":{"self":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts\/4058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/comments?post=4058"}],"version-history":[{"count":1,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts\/4058\/revisions"}],"predecessor-version":[{"id":4059,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts\/4058\/revisions\/4059"}],"wp:attachment":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/media?parent=4058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/categories?post=4058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/tags?post=4058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}