{"id":36665,"date":"2025-12-20T00:46:46","date_gmt":"2025-12-20T00:46:46","guid":{"rendered":"https:\/\/tabernaculoprensadedios.com\/web\/?p=36665"},"modified":"2025-12-20T00:46:46","modified_gmt":"2025-12-20T00:46:46","slug":"a-los-pies-de-la-cruz","status":"publish","type":"post","link":"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/","title":{"rendered":"A los pies de la Cruz"},"content":{"rendered":"<p>La cruz es m\u00e1s que un s\u00edmbolo, es el punto de partida del cristianismo que tiene como centro al Cristo redentor. Sin embargo, hoy en d\u00eda el evangelio se aleja cada vez m\u00e1s de la cruz y se predica un \u201cevangelio sin demandas\u201d, un evangelio diluido, adaptado a los placeres, una gracia barata. Vivir a los pies de la cruz significa morir al pecado y poner a Cristo en el primer lugar de nuestras vidas. Es crucificarnos, negarnos, tomar nuestra propia cruz para resucitar a una nueva vida, a una vida gloriosa. A medida que esto sucede, comienzan a surgir en nosotros virtudes cristianas que glorifican a Dios y a Cristo salvador.<\/p>\n<p>Si la cruz fue en alguna \u00e9poca del cristianismo la imagen del dolor y de la verg\u00fcenza, para el cristiano de hoy es s\u00edmbolo de esperanza y victoria. La salvaci\u00f3n se obtiene a partir de la cruz, en el reconocimiento del sacrificio de nuestro Se\u00f1or, quien en la cruz clav\u00f3 todos los pecados del mundo a trav\u00e9s de su sangre redentora. La cruz es m\u00e1s que un s\u00edmbolo, es el punto de partida del cristianismo que tiene como centro al Cristo redentor. Un hermoso documento de la Fraternidad Teol\u00f3gica Latinoamericana sentenci\u00f3 en 1985 en Brasil: \u201cla Cruz de Cristo, m\u00e1s que comprendida, debe ser asumida\u2026lo que significa adoptar la misma opci\u00f3n liberadora de Jes\u00fas que implica la identificaci\u00f3n con los d\u00e9biles, los desventurados y marginados\u201d. Los cristianos debemos vivir a los pies de la cruz. El mundo est\u00e1 demasiado entretenido en recrear sus miserias y depravaciones jug\u00e1ndose la vida. El evangelio que se predica hoy en tant\u00edsimos lugares se aleja cada vez m\u00e1s de la cruz. Es el \u201cevangelio sin demandas\u201d, un evangelio diluido, adaptado a los placeres, es una gracia barata, un nuevo evangelio, sin compromisos, donde la consagraci\u00f3n y el servicio son palabras obsoletas \u2013 como tambi\u00e9n dicen del pecado -, es un evangelio sin cruz.<\/p>\n<p>El evangelio sin cruz se niega a nombrar el pecado por su nombre, lo enmascara, lo oculta, lo convierte en una acci\u00f3n justificada porque \u201cla vida es muy corta y hay que vivirla a plenitud\u201d. Cristo compr\u00f3 nuestras vidas en la cruz y all\u00ed mismo le asest\u00f3 un golpe mortal al reino de las tinieblas al resucitar, al emerger de la cruz con una luz que nos ilumina desde el Calvario y hasta la eternidad. Por ah\u00ed andan quienes afirman que la palabra pecado est\u00e1 fuera de contexto, que ya no es actual, que debemos cuidarnos de herir a las personas cuando les decimos que son pecadoras y que deben arrepentirse, que es muy agresiva y a nadie le gusta escucharla. En ocasiones, mejor hablamos de reprender a los esp\u00edritus de fornicaci\u00f3n, de borrachera, de adulterio que de reprendernos a nosotros mimos por nuestros pecados. Somos nosotros los pecadores, no lo esp\u00edritus que solemos reprender como si el pecado no tuviera rostros. Actuamos como los g\u00e1latas insensatos, como si la Cruz y la sangre de Cristo no hubieran sido necesarias para limpiar nuestra propia corrupci\u00f3n. Hemos escuchado decir muchas veces \u201cestamos siendo afectados por el esp\u00edritu de enemistad, desamor, rivalidad, desconfianza, etc.\u201d \u00a1Caramba! \u00bfNo es mejor actuar a los pies de la Cruz y confrontar el pecado de cada cual con su poder liberador y de victoria llamando al pecador al arrepentimiento?<\/p>\n<p>De acuerdo al Pacto de Lausana \u201cuna iglesia que predica la cruz debe ella misma estar marcada por la cruz\u201d. \u00a1Qu\u00e9 desaf\u00edo m\u00e1s grande para la iglesia de Cristo y para todos los cristianos!<\/p>\n<p>Vivir a los pies de la cruz como disc\u00edpulos de Cristo significa en primer lugar \u201cmorir al pecado\u201d con los ojos puesto en el trono de nuestro salvador. La cruz es el trono de Jes\u00fas. Vivir a los pies de la cruz es hacer morir al \u201cyo\u201d, es poner a Cristo en el primer lugar de nuestras vidas y humillarnos como \u00e9l se humill\u00f3 para venir a este mundo a sufrir una muerte de cruz. Es \u201ccrucificarnos\u201d, \u201cnegarnos\u201d, tomar nuestra propia cruz\u201d para resucitar a una nueva vida, a una vida gloriosa. A medida que esto sucede comienzan a surgir en nosotros virtudes cristianas que glorifican a Dios y a Cristo salvador. Pablo nos ayuda a reflexionar sobre la cruz cuando dice: \u201cperseguidos, pero no abandonados; derribados, pero no destruidos. Dondequiera que vamos, siempre llevamos en nuestro cuerpo la muerte de Jes\u00fas, para que tambi\u00e9n su vida se manifieste en nuestro cuerpo.<strong> (2 Co 4:9-10) NVI)<\/strong><\/p>\n<p>Amados hermanos, a nosotros nos toca vivir a los pies de su cruz para ser dignos de tan grande salvaci\u00f3n y poder gritar a este convulso mundo: \u00a1Cristo vive! A \u00c9l sea la gloria por siempre y para siempre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cruz es m\u00e1s que un s\u00edmbolo, es el punto de partida del cristianismo que tiene como centro al Cristo redentor. Sin embargo, hoy en d\u00eda el evangelio se aleja cada vez m\u00e1s de la cruz y se predica un \u201cevangelio sin demandas\u201d, un evangelio diluido, adaptado a los placeres, una gracia barata. Vivir a &hellip;<\/p>\n","protected":false},"author":1,"featured_media":36666,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"class_list":["post-36665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>A los pies de la Cruz - Tabernaculo Prensa de Dios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"A los pies de la Cruz\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"La cruz es m\u00e1s que un s\u00edmbolo, es el punto de partida del cristianismo que tiene como centro al Cristo redentor. Sin embargo, hoy en d\u00eda el evangelio se aleja cada vez m\u00e1s de la cruz y se predica un \u201cevangelio sin demandas\u201d, un evangelio diluido, adaptado a los placeres, una gracia barata. Vivir a &hellip;\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Tabernaculo Prensa de Dios\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-20T00:46:46+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2025\/12\/A-los-pies-de-la-Cruz.avif\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"tabernaculo\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:creator\" content=\"@PrensadeDios\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:site\" content=\"@PrensadeDios\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"tabernaculo\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/\"},\"author\":{\"name\":\"tabernaculo\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e\"},\"headline\":\"A los pies de la Cruz\",\"datePublished\":\"2025-12-20T00:46:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/\"},\"wordCount\":821,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e\"},\"image\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2025\/12\/A-los-pies-de-la-Cruz.avif\",\"articleSection\":[\"Articulos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/\",\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/\",\"name\":\"A los pies de la Cruz - Tabernaculo Prensa de Dios\",\"isPartOf\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2025\/12\/A-los-pies-de-la-Cruz.avif\",\"datePublished\":\"2025-12-20T00:46:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/#primaryimage\",\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2025\/12\/A-los-pies-de-la-Cruz.avif\",\"contentUrl\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2025\/12\/A-los-pies-de-la-Cruz.avif\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/tabernaculoprensadedios.com\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A los pies de la Cruz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#website\",\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/\",\"name\":\"Tabernaculo Prensa de Dios\",\"description\":\"Un medio a la manera de Dios\",\"publisher\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tabernaculoprensadedios.com\/web\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e\",\"name\":\"tabernaculo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png\",\"contentUrl\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png\",\"width\":300,\"height\":118,\"caption\":\"tabernaculo\"},\"logo\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/image\/\"},\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/author\/tabernaculo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"A los pies de la Cruz - Tabernaculo Prensa de Dios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/","og_locale":"es_ES","og_type":"article","og_title":"A los pies de la Cruz","og_description":"La cruz es m\u00e1s que un s\u00edmbolo, es el punto de partida del cristianismo que tiene como centro al Cristo redentor. Sin embargo, hoy en d\u00eda el evangelio se aleja cada vez m\u00e1s de la cruz y se predica un \u201cevangelio sin demandas\u201d, un evangelio diluido, adaptado a los placeres, una gracia barata. Vivir a &hellip;","og_url":"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/","og_site_name":"Tabernaculo Prensa de Dios","article_published_time":"2025-12-20T00:46:46+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2025\/12\/A-los-pies-de-la-Cruz.avif","type":"image\/jpeg"}],"author":"tabernaculo","twitter_card":"summary_large_image","twitter_creator":"@PrensadeDios","twitter_site":"@PrensadeDios","twitter_misc":{"Escrito por":"tabernaculo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/#article","isPartOf":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/"},"author":{"name":"tabernaculo","@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e"},"headline":"A los pies de la Cruz","datePublished":"2025-12-20T00:46:46+00:00","mainEntityOfPage":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/"},"wordCount":821,"commentCount":0,"publisher":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e"},"image":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/#primaryimage"},"thumbnailUrl":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2025\/12\/A-los-pies-de-la-Cruz.avif","articleSection":["Articulos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/","url":"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/","name":"A los pies de la Cruz - Tabernaculo Prensa de Dios","isPartOf":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/#primaryimage"},"image":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/#primaryimage"},"thumbnailUrl":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2025\/12\/A-los-pies-de-la-Cruz.avif","datePublished":"2025-12-20T00:46:46+00:00","breadcrumb":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/#primaryimage","url":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2025\/12\/A-los-pies-de-la-Cruz.avif","contentUrl":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2025\/12\/A-los-pies-de-la-Cruz.avif","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/tabernaculoprensadedios.com\/web\/a-los-pies-de-la-cruz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tabernaculoprensadedios.com\/web\/"},{"@type":"ListItem","position":2,"name":"A los pies de la Cruz"}]},{"@type":"WebSite","@id":"https:\/\/tabernaculoprensadedios.com\/web\/#website","url":"https:\/\/tabernaculoprensadedios.com\/web\/","name":"Tabernaculo Prensa de Dios","description":"Un medio a la manera de Dios","publisher":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tabernaculoprensadedios.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e","name":"tabernaculo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/image\/","url":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png","contentUrl":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png","width":300,"height":118,"caption":"tabernaculo"},"logo":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/image\/"},"url":"https:\/\/tabernaculoprensadedios.com\/web\/author\/tabernaculo\/"}]}},"_links":{"self":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts\/36665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/comments?post=36665"}],"version-history":[{"count":1,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts\/36665\/revisions"}],"predecessor-version":[{"id":36667,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts\/36665\/revisions\/36667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/media\/36666"}],"wp:attachment":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/media?parent=36665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/categories?post=36665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/tags?post=36665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}