{"id":30076,"date":"2024-01-26T18:07:38","date_gmt":"2024-01-26T18:07:38","guid":{"rendered":"https:\/\/tabernaculoprensadedios.com\/web\/?p=30076"},"modified":"2024-01-30T16:34:07","modified_gmt":"2024-01-30T16:34:07","slug":"juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2","status":"publish","type":"post","link":"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/","title":{"rendered":"Juan Pablo Duarte: Bandera de la Libertad de Rep\u00fablica Dominicana"},"content":{"rendered":"<p><strong>Hace 211 a\u00f1os naci\u00f3 un ni\u00f1o de familia acomodada,<\/strong> que sin saberlo, iba a ser el redentor de su patria. En la mitolog\u00eda grecorromana, hab\u00eda tres mujeres que s\u00f3lo se la pasaban cosiendo, que se llamaban las parcas. Una hilaba y daba una primera puntada (nacimiento), otra desarrollaba el tejido multicolor de la vida, y otra cortaba el hilo (la muerte).<\/p>\n<p>Cuando Juan Pablo nace, su patria era una olvidada colonia que hab\u00eda cambiado varias veces de manos y era sumamente pobre y sufrida. Aunque ten\u00eda bienes para vivir con holgura, siempre luch\u00f3 en pro de la patria, entregando todo lo que ten\u00eda en pro de esa misi\u00f3n sacrosanta de la libertad.<\/p>\n<p><strong>Duarte, contrario a lo que se cree, nunca fue antihaitiano.<\/strong> Siempre manifest\u00f3 que admiraba la lucha del pueblo haitiano por su libertad, y que era enemigo de que el pueblo haitiano le negara a los dominicanos la oportunidad de autodeterminarse.<\/p>\n<p>Si analizamos su vida, muy movida y azarosa, <strong>s\u00f3lo tuvo gravitaci\u00f3n pol\u00edtica entre 1838 y 1843, algunos meses de 1844 y cuando regresa en 1861,<\/strong> pasando la mayor parte de su vida adulta en la selva y luego enfermo, pero con esos pocos a\u00f1os nos leg\u00f3 un ideal de patria que debemos defender.<\/p>\n<p>Cuando llegue el 26 de enero, cada dominicano, doquiera est\u00e9, debe rendirle homenaje a ese joven estudiado, que sacrific\u00f3 un futuro prometedor, para darnos una nacionalidad y unir a nuestro pueblo.<\/p>\n<p>Hoy, todos los dominicanos, m\u00e1s all\u00e1 de nuestras diferencias, siempre podremos buscar como ejemplo al patricio desinteresado, aquel que nunca dud\u00f3 de que merec\u00edamos ser libres e independientes, que pod\u00edamos ser pr\u00f3speros y ser un ejemplo bajo el influjo de la raz\u00f3n y de la fe.<strong> Por ello, esa cruz en el medio de la bandera, ese signo de redenci\u00f3n y amor.<\/strong><\/p>\n<p>En resumen, dominicano, recuerda que gracias a ese joven te puedes llamar as\u00ed, por lo que debes cuidar su legado y traspasarlo a las futuras generaciones. <strong>Esa es la mejor forma de honrarlo. Hacer patria cada d\u00eda.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace 211 a\u00f1os naci\u00f3 un ni\u00f1o de familia acomodada, que sin saberlo, iba a ser el redentor de su patria. En la mitolog\u00eda grecorromana, hab\u00eda tres mujeres que s\u00f3lo se la pasaban cosiendo, que se llamaban las parcas. Una hilaba y daba una primera puntada (nacimiento), otra desarrollaba el tejido multicolor de la vida, y &hellip;<\/p>\n","protected":false},"author":1,"featured_media":5410,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-30076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Juan Pablo Duarte: Bandera de la Libertad de Rep\u00fablica Dominicana - Tabernaculo Prensa de Dios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Juan Pablo Duarte: Bandera de la Libertad de Rep\u00fablica Dominicana\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Hace 211 a\u00f1os naci\u00f3 un ni\u00f1o de familia acomodada, que sin saberlo, iba a ser el redentor de su patria. En la mitolog\u00eda grecorromana, hab\u00eda tres mujeres que s\u00f3lo se la pasaban cosiendo, que se llamaban las parcas. Una hilaba y daba una primera puntada (nacimiento), otra desarrollaba el tejido multicolor de la vida, y &hellip;\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Tabernaculo Prensa de Dios\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-26T18:07:38+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-30T16:34:07+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/02\/Juan-Pablo-Duarte-Bandera-de-la-Libertad-Dominicana.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"772\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"tabernaculo\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:creator\" content=\"@PrensadeDios\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:site\" content=\"@PrensadeDios\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"tabernaculo\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/\"},\"author\":{\"name\":\"tabernaculo\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e\"},\"headline\":\"Juan Pablo Duarte: Bandera de la Libertad de Rep\u00fablica Dominicana\",\"datePublished\":\"2024-01-26T18:07:38+00:00\",\"dateModified\":\"2024-01-30T16:34:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/\"},\"wordCount\":360,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e\"},\"image\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/02\/Juan-Pablo-Duarte-Bandera-de-la-Libertad-Dominicana.jpg\",\"articleSection\":[\"Politica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/\",\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/\",\"name\":\"Juan Pablo Duarte: Bandera de la Libertad de Rep\u00fablica Dominicana - Tabernaculo Prensa de Dios\",\"isPartOf\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/02\/Juan-Pablo-Duarte-Bandera-de-la-Libertad-Dominicana.jpg\",\"datePublished\":\"2024-01-26T18:07:38+00:00\",\"dateModified\":\"2024-01-30T16:34:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/#primaryimage\",\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/02\/Juan-Pablo-Duarte-Bandera-de-la-Libertad-Dominicana.jpg\",\"contentUrl\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/02\/Juan-Pablo-Duarte-Bandera-de-la-Libertad-Dominicana.jpg\",\"width\":772,\"height\":580,\"caption\":\"Carta de triunfo para gobernar una naci\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/tabernaculoprensadedios.com\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juan Pablo Duarte: Bandera de la Libertad de Rep\u00fablica Dominicana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#website\",\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/\",\"name\":\"Tabernaculo Prensa de Dios\",\"description\":\"Un medio a la manera de Dios\",\"publisher\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tabernaculoprensadedios.com\/web\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e\",\"name\":\"tabernaculo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png\",\"contentUrl\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png\",\"width\":300,\"height\":118,\"caption\":\"tabernaculo\"},\"logo\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/image\/\"},\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/author\/tabernaculo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Juan Pablo Duarte: Bandera de la Libertad de Rep\u00fablica Dominicana - Tabernaculo Prensa de Dios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/","og_locale":"es_ES","og_type":"article","og_title":"Juan Pablo Duarte: Bandera de la Libertad de Rep\u00fablica Dominicana","og_description":"Hace 211 a\u00f1os naci\u00f3 un ni\u00f1o de familia acomodada, que sin saberlo, iba a ser el redentor de su patria. En la mitolog\u00eda grecorromana, hab\u00eda tres mujeres que s\u00f3lo se la pasaban cosiendo, que se llamaban las parcas. Una hilaba y daba una primera puntada (nacimiento), otra desarrollaba el tejido multicolor de la vida, y &hellip;","og_url":"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/","og_site_name":"Tabernaculo Prensa de Dios","article_published_time":"2024-01-26T18:07:38+00:00","article_modified_time":"2024-01-30T16:34:07+00:00","og_image":[{"width":772,"height":580,"url":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/02\/Juan-Pablo-Duarte-Bandera-de-la-Libertad-Dominicana.jpg","type":"image\/jpeg"}],"author":"tabernaculo","twitter_card":"summary_large_image","twitter_creator":"@PrensadeDios","twitter_site":"@PrensadeDios","twitter_misc":{"Escrito por":"tabernaculo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/#article","isPartOf":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/"},"author":{"name":"tabernaculo","@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e"},"headline":"Juan Pablo Duarte: Bandera de la Libertad de Rep\u00fablica Dominicana","datePublished":"2024-01-26T18:07:38+00:00","dateModified":"2024-01-30T16:34:07+00:00","mainEntityOfPage":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/"},"wordCount":360,"commentCount":0,"publisher":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e"},"image":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/#primaryimage"},"thumbnailUrl":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/02\/Juan-Pablo-Duarte-Bandera-de-la-Libertad-Dominicana.jpg","articleSection":["Politica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/","url":"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/","name":"Juan Pablo Duarte: Bandera de la Libertad de Rep\u00fablica Dominicana - Tabernaculo Prensa de Dios","isPartOf":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/#primaryimage"},"image":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/#primaryimage"},"thumbnailUrl":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/02\/Juan-Pablo-Duarte-Bandera-de-la-Libertad-Dominicana.jpg","datePublished":"2024-01-26T18:07:38+00:00","dateModified":"2024-01-30T16:34:07+00:00","breadcrumb":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/#primaryimage","url":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/02\/Juan-Pablo-Duarte-Bandera-de-la-Libertad-Dominicana.jpg","contentUrl":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/02\/Juan-Pablo-Duarte-Bandera-de-la-Libertad-Dominicana.jpg","width":772,"height":580,"caption":"Carta de triunfo para gobernar una naci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/tabernaculoprensadedios.com\/web\/juan-pablo-duarte-bandera-de-la-libertad-de-republica-dominicana-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tabernaculoprensadedios.com\/web\/"},{"@type":"ListItem","position":2,"name":"Juan Pablo Duarte: Bandera de la Libertad de Rep\u00fablica Dominicana"}]},{"@type":"WebSite","@id":"https:\/\/tabernaculoprensadedios.com\/web\/#website","url":"https:\/\/tabernaculoprensadedios.com\/web\/","name":"Tabernaculo Prensa de Dios","description":"Un medio a la manera de Dios","publisher":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tabernaculoprensadedios.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e","name":"tabernaculo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/image\/","url":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png","contentUrl":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png","width":300,"height":118,"caption":"tabernaculo"},"logo":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/image\/"},"url":"https:\/\/tabernaculoprensadedios.com\/web\/author\/tabernaculo\/"}]}},"_links":{"self":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts\/30076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/comments?post=30076"}],"version-history":[{"count":1,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts\/30076\/revisions"}],"predecessor-version":[{"id":30077,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts\/30076\/revisions\/30077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/media\/5410"}],"wp:attachment":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/media?parent=30076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/categories?post=30076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/tags?post=30076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}