{"id":10751,"date":"2018-11-15T02:26:09","date_gmt":"2018-11-15T02:26:09","guid":{"rendered":"http:\/\/tabernaculoprensadedios.com\/web\/?p=10751"},"modified":"2018-11-15T02:26:09","modified_gmt":"2018-11-15T02:26:09","slug":"diferencias-que-distinguen","status":"publish","type":"post","link":"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/","title":{"rendered":"Diferencias que distinguen"},"content":{"rendered":"<p><em>\u00abPorque el jud\u00edo Mardoqueo era el segundo despu\u00e9s del rey Asuero, grande entre los jud\u00edos y estimado por la multitud de sus hermanos, el cual busc\u00f3 el bien de su pueblo y procur\u00f3 el bienestar de toda su gente<\/em>\u00bb <strong>Ester 10:3<\/strong> (LBLA)<\/p>\n<p>Mardoqueo dej\u00f3 un gran legado, no solo a Ester, sino a toda su generaci\u00f3n, modelando los principios que deb\u00edan diferenciarlos como pueblo de Dios, fue un hombre \u00edntegro y comprometido, que ante todo, busc\u00f3 el bien de su gente y que no negoci\u00f3 la Ley de Dios. \u00bfQu\u00e9 legado estamos pasando a nuestras generaciones? \u00bfC\u00f3mo impactaremos sus vidas? \u00bfOtros pueden realmente ver cu\u00e1nto amamos a Dios? \u00bfQu\u00e9 principios divinos vivimos con gozo y amor? \u00bfSer\u00e1 que solo nos ven como religiosos que vamos a ocupar una silla cada domingo a la iglesia y no han visto nuestro deseo de reflejar al Se\u00f1or y c\u00f3mo vamos caminando hacia esa meta a trav\u00e9s de peque\u00f1os pasos, a pesar de que muchas veces tropezamos? \u00bfEstamos reflejando a Cristo en nuestros trabajos, estudios, familia, amigos? Mardoqueo no menciona a Dios, Ester tampoco&#8230; Pero lo glorifican en todo momento con sus conductas. No es por lo que hablemos, es por los frutos que sabr\u00e1n si somos o no Sus disc\u00edpulos, si somos cristianos verdaderos.<\/p>\n<p><strong>\u00a0<\/strong><strong>Oraci\u00f3n<br \/>\n<\/strong>Se\u00f1or, me postro ante Ti para pedirte perd\u00f3n por cada palabra, pensamiento y acci\u00f3n que no Te ha glorificado. Te ruego Esp\u00edritu Santo que me ayudes a caminar en Santidad y a glorificarte en todo lo que haga o deje de hacer, que mi coraz\u00f3n permanezca inundado de Ti, que mi mente se enfoque completamente en Ti, que mis acciones sean dirigidas por Ti, que pueda dejar un legado digno de Ti a mis generaciones para que Te busquen, Te conozcan y sigan, Te lo pido en el Nombre de Jes\u00fas. \u00a1Am\u00e9n!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abPorque el jud\u00edo Mardoqueo era el segundo despu\u00e9s del rey Asuero, grande entre los jud\u00edos y estimado por la multitud de sus hermanos, el cual busc\u00f3 el bien de su pueblo y procur\u00f3 el bienestar de toda su gente\u00bb Ester 10:3 (LBLA) Mardoqueo dej\u00f3 un gran legado, no solo a Ester, sino a toda su &hellip;<\/p>\n","protected":false},"author":1,"featured_media":10752,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"class_list":["post-10751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Diferencias que distinguen - Tabernaculo Prensa de Dios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Diferencias que distinguen\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"\u00abPorque el jud\u00edo Mardoqueo era el segundo despu\u00e9s del rey Asuero, grande entre los jud\u00edos y estimado por la multitud de sus hermanos, el cual busc\u00f3 el bien de su pueblo y procur\u00f3 el bienestar de toda su gente\u00bb Ester 10:3 (LBLA) Mardoqueo dej\u00f3 un gran legado, no solo a Ester, sino a toda su &hellip;\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Tabernaculo Prensa de Dios\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-15T02:26:09+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/distinguen.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"598\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"tabernaculo\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:creator\" content=\"@PrensadeDios\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:site\" content=\"@PrensadeDios\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"tabernaculo\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/\"},\"author\":{\"name\":\"tabernaculo\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e\"},\"headline\":\"Diferencias que distinguen\",\"datePublished\":\"2018-11-15T02:26:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/\"},\"wordCount\":327,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e\"},\"image\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/distinguen.jpg\",\"articleSection\":[\"Articulos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/\",\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/\",\"name\":\"Diferencias que distinguen - Tabernaculo Prensa de Dios\",\"isPartOf\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/distinguen.jpg\",\"datePublished\":\"2018-11-15T02:26:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/#primaryimage\",\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/distinguen.jpg\",\"contentUrl\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/distinguen.jpg\",\"width\":960,\"height\":598},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/tabernaculoprensadedios.com\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diferencias que distinguen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#website\",\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/\",\"name\":\"Tabernaculo Prensa de Dios\",\"description\":\"Un medio a la manera de Dios\",\"publisher\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tabernaculoprensadedios.com\/web\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e\",\"name\":\"tabernaculo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png\",\"contentUrl\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png\",\"width\":300,\"height\":118,\"caption\":\"tabernaculo\"},\"logo\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/image\/\"},\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/author\/tabernaculo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Diferencias que distinguen - Tabernaculo Prensa de Dios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/","og_locale":"es_ES","og_type":"article","og_title":"Diferencias que distinguen","og_description":"\u00abPorque el jud\u00edo Mardoqueo era el segundo despu\u00e9s del rey Asuero, grande entre los jud\u00edos y estimado por la multitud de sus hermanos, el cual busc\u00f3 el bien de su pueblo y procur\u00f3 el bienestar de toda su gente\u00bb Ester 10:3 (LBLA) Mardoqueo dej\u00f3 un gran legado, no solo a Ester, sino a toda su &hellip;","og_url":"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/","og_site_name":"Tabernaculo Prensa de Dios","article_published_time":"2018-11-15T02:26:09+00:00","og_image":[{"width":960,"height":598,"url":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/distinguen.jpg","type":"image\/jpeg"}],"author":"tabernaculo","twitter_card":"summary_large_image","twitter_creator":"@PrensadeDios","twitter_site":"@PrensadeDios","twitter_misc":{"Escrito por":"tabernaculo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/#article","isPartOf":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/"},"author":{"name":"tabernaculo","@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e"},"headline":"Diferencias que distinguen","datePublished":"2018-11-15T02:26:09+00:00","mainEntityOfPage":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/"},"wordCount":327,"commentCount":0,"publisher":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e"},"image":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/#primaryimage"},"thumbnailUrl":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/distinguen.jpg","articleSection":["Articulos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/","url":"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/","name":"Diferencias que distinguen - Tabernaculo Prensa de Dios","isPartOf":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/#primaryimage"},"image":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/#primaryimage"},"thumbnailUrl":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/distinguen.jpg","datePublished":"2018-11-15T02:26:09+00:00","breadcrumb":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/#primaryimage","url":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/distinguen.jpg","contentUrl":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/distinguen.jpg","width":960,"height":598},{"@type":"BreadcrumbList","@id":"https:\/\/tabernaculoprensadedios.com\/web\/diferencias-que-distinguen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tabernaculoprensadedios.com\/web\/"},{"@type":"ListItem","position":2,"name":"Diferencias que distinguen"}]},{"@type":"WebSite","@id":"https:\/\/tabernaculoprensadedios.com\/web\/#website","url":"https:\/\/tabernaculoprensadedios.com\/web\/","name":"Tabernaculo Prensa de Dios","description":"Un medio a la manera de Dios","publisher":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tabernaculoprensadedios.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e","name":"tabernaculo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/image\/","url":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png","contentUrl":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png","width":300,"height":118,"caption":"tabernaculo"},"logo":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/image\/"},"url":"https:\/\/tabernaculoprensadedios.com\/web\/author\/tabernaculo\/"}]}},"_links":{"self":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts\/10751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/comments?post=10751"}],"version-history":[{"count":1,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts\/10751\/revisions"}],"predecessor-version":[{"id":10753,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts\/10751\/revisions\/10753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/media\/10752"}],"wp:attachment":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/media?parent=10751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/categories?post=10751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/tags?post=10751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}