{"id":10727,"date":"2018-11-13T00:58:29","date_gmt":"2018-11-13T00:58:29","guid":{"rendered":"http:\/\/tabernaculoprensadedios.com\/web\/?p=10727"},"modified":"2018-11-13T00:59:27","modified_gmt":"2018-11-13T00:59:27","slug":"y-alabo-el-amo-al-mayordomo-malo","status":"publish","type":"post","link":"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/","title":{"rendered":"\u201cY alab\u00f3 el amo al mayordomo malo\u2026\u201d"},"content":{"rendered":"<p>En <strong>Lucas 16<\/strong>, vemos la par\u00e1bola del mayordomo infiel, en la que se acusa al mayordomo de malgastar los bienes de su amo, quien le pide cuentas y dice que le quitar\u00e1 la mayordom\u00eda. Es entonces que el mayordomo decide reescribir las deudas de los deudores de su amo por unas m\u00e1s bajas, para que cuando se le quitara la mayordom\u00eda le recibieran en sus casas.<\/p>\n<p>\u201c8 Y alab\u00f3 el amo al mayordomo malo por haber hecho sagazmente; porque los hijos de este siglo son m\u00e1s sagaces en el trato con sus semejantes que los hijos de luz. 9 Y yo os digo: Ganad amigos por medio de las riquezas injustas, para que cuando \u00e9stas falten, os reciban en las moradas eternas.\u201d <strong>Lucas 16:8-9<\/strong><\/p>\n<p>Jes\u00fas est\u00e1 ense\u00f1ando aqu\u00ed c\u00f3mo el mundo es m\u00e1s inteligente con las finanzas que los cristianos; lo hacen mal, pero son m\u00e1s inteligentes, m\u00e1s sagaces. Los amigos de los que habla, no son los de la tierra; Jes\u00fas est\u00e1 llevando esta representaci\u00f3n a un nivel espiritual. Jes\u00fas estaba diciendo que con las riquezas injustas te asegures la eternidad porque, cuando no tengas las riquezas, debes tener algo que las reemplace; y las riquezas injustas te dan moradas en la eternidad.<\/p>\n<p>\u201c10 El que es fiel en lo muy poco, tambi\u00e9n en lo m\u00e1s es fiel; y el que en lo muy poco es injusto, tambi\u00e9n en lo m\u00e1s es injusto. 11 Pues si en las riquezas injustas no fuisteis fieles, \u00bfqui\u00e9n os confiar\u00e1 lo verdadero? 12 Y si en lo ajeno no fuisteis fieles, \u00bfqui\u00e9n os dar\u00e1 lo que es vuestro? 13 Ning\u00fan siervo puede servir a dos se\u00f1ores; porque o aborrecer\u00e1 al uno y amar\u00e1 al otro, o estimar\u00e1 al uno y menospreciar\u00e1 al otro. No pod\u00e9is servir a Dios y a las riquezas.\u201d <strong>Lucas 16:10-13 <\/strong><\/p>\n<p>Cuando habla de riquezas injustas, lo que habla es de riquezas naturales; y \u00bfc\u00f3mo Dios puede confiar lo verdadero, lo real, si t\u00fa no demuestras que con las riquezas naturales eres fiel? \u00bfC\u00f3mo dices que vas a ser empresario, si no fuiste fiel en el trabajo? \u00bfC\u00f3mo dices que vas a ser pastor, si no fuiste fiel en la iglesia a la que asist\u00edas? Si no eres fiel con lo que no es tuyo, \u00bfc\u00f3mo Dios te va a dar algo que s\u00ed lo sea?<\/p>\n<p>Vemos a Dios alabando a alguien que est\u00e1 haciendo algo incorrecto; dice que ganemos moradas eternas con las riquezas injustas. \u00bfQu\u00e9 es lo que est\u00e1 diciendo el Se\u00f1or? Dios te quiere prosperar, pero no es que te vaya a llegar el dinero del cielo, y no vayas a ser responsable de \u00e9l. T\u00fa tienes que honrar a Dios con c\u00f3mo produces dinero, honrarle con el dinero, y todos tus gastos e inversiones tienen que honrarle tambi\u00e9n. Y en esta par\u00e1bola vemos 4 cosas que nos ayudan a mantener este par\u00e1metro bien claro:<\/p>\n<p>Todos, alg\u00fan d\u00eda, tendremos que darle cuenta a Dios de todo lo que \u00c9l puso en nuestra mano. En toda par\u00e1bola de mayordomos, siempre el amo llama a cuentas a los mayordomos. Dios te da rienda, pero alg\u00fan d\u00eda \u00c9l te va a llamar a cuentas.<\/p>\n<p>Jes\u00fas admir\u00f3 en este hombre \u2013quien rob\u00f3 al amo \u2013 la utilizaci\u00f3n de las finanzas para crear nuevas oportunidades. Dijo: Este hombre es sagaz; sabe que lo voy a botar, y utiliz\u00f3 el dinero para crearse una nueva oportunidad. Cuando t\u00fa te vayas para el cielo, ya t\u00fa perdiste toda oportunidad. Las \u00fanicas oportunidades que t\u00fa tienes, las tienes aqu\u00ed en la tierra; y, mientras est\u00e1s aqu\u00ed, el dinero tienes que usarlo para crear nuevas oportunidades mientras lo tengas; porque no siempre lo vas a tener. Con tu salario, lo importante es crear nuevas oportunidades, relaciones, amistades. No almuerces solo; almuerza siempre con alguien. Crea relaciones, invierte en ellas. No lo hagas esperando algo inmediatamente, eso ser\u00eda manipulaci\u00f3n; pero hazlo, s\u00e9 sagaz. Mientras tengas la oportunidad, haz con ella algo eterno.<\/p>\n<p>Dios se va a encargar de hacer que alguien te lo pague alg\u00fan d\u00eda.<\/p>\n<p>El Se\u00f1or dice claramente que, si t\u00fa no sabes manejar las riquezas injustas, \u00bfc\u00f3mo puede darte las verdaderas? En el Nuevo Testamento, Pablo habla de las riquezas del poder de Dios, de la unci\u00f3n, de la gloria, que est\u00e1n guardadas para nosotros. Si t\u00fa no sabes usar un d\u00f3lar, \u00bfc\u00f3mo Dios te puede dar su unci\u00f3n? Las riquezas de la gloria de Dios son sabidur\u00eda, conocimiento; cosas m\u00e1s poderosas que el dinero; pero tambi\u00e9n m\u00e1s peligrosas. Si t\u00fa no sabes manejar el conocimiento que tienes, es m\u00e1s peligroso que un d\u00f3lar. Y \u00bfc\u00f3mo, si t\u00fa no has demostrado que en lo peque\u00f1o eres fiel, Dios puede darte grande unci\u00f3n? Gente que tiene verdadera unci\u00f3n, autoridad, poder en el Evangelio, por lo general, son buenos administradores y fieles en todo lo que hacen. Nadie llega a ese lugar haciendo las cosas mal; y el que las hace mal, alg\u00fan d\u00eda paga, y cuando paga, te desilusionas y te das cuenta que no era tanta la unci\u00f3n que ten\u00eda. As\u00ed que, si t\u00fa quieres lo verdadero de Dios, cada d\u00f3lar que tienes en tu mano tienes que utilizarlo correctamente.<\/p>\n<p>Dios desea que escojas servirle a \u00c9l con tu mayordom\u00eda. No puedes tener 2 se\u00f1ores. Dios nunca se va a imponer; su se\u00f1or\u00edo no se impone sobre tu vida. \u00c9l te da dinero para que t\u00fa escojas a qui\u00e9n le sirves. Dios no es como el gobierno, que te quita el impuesto; Dios te da la oportunidad que t\u00fa decidas. No recientas al gobierno por los impuestos que tienes que pagar; cuando pagas m\u00e1s impuestos, da gracias a Dios porque eso lo que significa es que ganaste m\u00e1s. El mediocre y el pobre recienten cada impuesto que pagan; cada vez que se lo exigen y se lo quitan, lo recienten; y Dios, para que t\u00fa no lo recientas, te da la oportunidad de que t\u00fa escojas si le honras. Por eso, el que da, debe darlo con alegr\u00eda porque Dios ama al dador alegre. El que diezma, lo que le dice a Dios es: T\u00fa eres mi Se\u00f1or, yo escojo servirte a ti, honrarte a ti con todo lo que tengo.<\/p>\n<p>Si t\u00fa aprendes hoy estos 4 puntos, las finanzas van a fluir en tu vida. Si t\u00fa las tienes claras en tu consciencia, Dios va a hacer que las ventanas de los cielos se abran sobre tu vida, y se derrame bendici\u00f3n hasta que sobreabunde.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Lucas 16, vemos la par\u00e1bola del mayordomo infiel, en la que se acusa al mayordomo de malgastar los bienes de su amo, quien le pide cuentas y dice que le quitar\u00e1 la mayordom\u00eda. Es entonces que el mayordomo decide reescribir las deudas de los deudores de su amo por unas m\u00e1s bajas, para que &hellip;<\/p>\n","protected":false},"author":1,"featured_media":10728,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"class_list":["post-10727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u201cY alab\u00f3 el amo al mayordomo malo\u2026\u201d - Tabernaculo Prensa de Dios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"\u201cY alab\u00f3 el amo al mayordomo malo\u2026\u201d\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"En Lucas 16, vemos la par\u00e1bola del mayordomo infiel, en la que se acusa al mayordomo de malgastar los bienes de su amo, quien le pide cuentas y dice que le quitar\u00e1 la mayordom\u00eda. Es entonces que el mayordomo decide reescribir las deudas de los deudores de su amo por unas m\u00e1s bajas, para que &hellip;\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Tabernaculo Prensa de Dios\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-13T00:58:29+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-13T00:59:27+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/yalabo.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"569\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"tabernaculo\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:creator\" content=\"@PrensadeDios\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:site\" content=\"@PrensadeDios\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"tabernaculo\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/\"},\"author\":{\"name\":\"tabernaculo\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e\"},\"headline\":\"\u201cY alab\u00f3 el amo al mayordomo malo\u2026\u201d\",\"datePublished\":\"2018-11-13T00:58:29+00:00\",\"dateModified\":\"2018-11-13T00:59:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/\"},\"wordCount\":1145,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e\"},\"image\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/yalabo.jpg\",\"articleSection\":[\"Articulos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/\",\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/\",\"name\":\"\u201cY alab\u00f3 el amo al mayordomo malo\u2026\u201d - Tabernaculo Prensa de Dios\",\"isPartOf\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/yalabo.jpg\",\"datePublished\":\"2018-11-13T00:58:29+00:00\",\"dateModified\":\"2018-11-13T00:59:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/#primaryimage\",\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/yalabo.jpg\",\"contentUrl\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/yalabo.jpg\",\"width\":960,\"height\":569},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/tabernaculoprensadedios.com\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cY alab\u00f3 el amo al mayordomo malo\u2026\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#website\",\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/\",\"name\":\"Tabernaculo Prensa de Dios\",\"description\":\"Un medio a la manera de Dios\",\"publisher\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tabernaculoprensadedios.com\/web\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e\",\"name\":\"tabernaculo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png\",\"contentUrl\":\"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png\",\"width\":300,\"height\":118,\"caption\":\"tabernaculo\"},\"logo\":{\"@id\":\"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/image\/\"},\"url\":\"https:\/\/tabernaculoprensadedios.com\/web\/author\/tabernaculo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u201cY alab\u00f3 el amo al mayordomo malo\u2026\u201d - Tabernaculo Prensa de Dios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cY alab\u00f3 el amo al mayordomo malo\u2026\u201d","og_description":"En Lucas 16, vemos la par\u00e1bola del mayordomo infiel, en la que se acusa al mayordomo de malgastar los bienes de su amo, quien le pide cuentas y dice que le quitar\u00e1 la mayordom\u00eda. Es entonces que el mayordomo decide reescribir las deudas de los deudores de su amo por unas m\u00e1s bajas, para que &hellip;","og_url":"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/","og_site_name":"Tabernaculo Prensa de Dios","article_published_time":"2018-11-13T00:58:29+00:00","article_modified_time":"2018-11-13T00:59:27+00:00","og_image":[{"width":960,"height":569,"url":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/yalabo.jpg","type":"image\/jpeg"}],"author":"tabernaculo","twitter_card":"summary_large_image","twitter_creator":"@PrensadeDios","twitter_site":"@PrensadeDios","twitter_misc":{"Escrito por":"tabernaculo","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/#article","isPartOf":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/"},"author":{"name":"tabernaculo","@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e"},"headline":"\u201cY alab\u00f3 el amo al mayordomo malo\u2026\u201d","datePublished":"2018-11-13T00:58:29+00:00","dateModified":"2018-11-13T00:59:27+00:00","mainEntityOfPage":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/"},"wordCount":1145,"commentCount":0,"publisher":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e"},"image":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/#primaryimage"},"thumbnailUrl":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/yalabo.jpg","articleSection":["Articulos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/","url":"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/","name":"\u201cY alab\u00f3 el amo al mayordomo malo\u2026\u201d - Tabernaculo Prensa de Dios","isPartOf":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/#primaryimage"},"image":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/#primaryimage"},"thumbnailUrl":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/yalabo.jpg","datePublished":"2018-11-13T00:58:29+00:00","dateModified":"2018-11-13T00:59:27+00:00","breadcrumb":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/#primaryimage","url":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/yalabo.jpg","contentUrl":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2018\/11\/yalabo.jpg","width":960,"height":569},{"@type":"BreadcrumbList","@id":"https:\/\/tabernaculoprensadedios.com\/web\/y-alabo-el-amo-al-mayordomo-malo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tabernaculoprensadedios.com\/web\/"},{"@type":"ListItem","position":2,"name":"\u201cY alab\u00f3 el amo al mayordomo malo\u2026\u201d"}]},{"@type":"WebSite","@id":"https:\/\/tabernaculoprensadedios.com\/web\/#website","url":"https:\/\/tabernaculoprensadedios.com\/web\/","name":"Tabernaculo Prensa de Dios","description":"Un medio a la manera de Dios","publisher":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tabernaculoprensadedios.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/bc0e069fef56b38e177db6f098ae0b6e","name":"tabernaculo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/image\/","url":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png","contentUrl":"https:\/\/tabernaculoprensadedios.com\/web\/wp-content\/uploads\/2015\/06\/login-logo1.png","width":300,"height":118,"caption":"tabernaculo"},"logo":{"@id":"https:\/\/tabernaculoprensadedios.com\/web\/#\/schema\/person\/image\/"},"url":"https:\/\/tabernaculoprensadedios.com\/web\/author\/tabernaculo\/"}]}},"_links":{"self":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts\/10727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/comments?post=10727"}],"version-history":[{"count":1,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts\/10727\/revisions"}],"predecessor-version":[{"id":10729,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/posts\/10727\/revisions\/10729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/media\/10728"}],"wp:attachment":[{"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/media?parent=10727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/categories?post=10727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tabernaculoprensadedios.com\/web\/wp-json\/wp\/v2\/tags?post=10727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}